{"id":5295,"date":"2025-05-06T11:29:33","date_gmt":"2025-05-06T09:29:33","guid":{"rendered":"https:\/\/www.precura.be\/newsletter-april-2025\/"},"modified":"2025-05-06T12:02:56","modified_gmt":"2025-05-06T10:02:56","slug":"newsletter-avril-2025","status":"publish","type":"post","link":"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/","title":{"rendered":"Newsletter Avril 2025"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.20.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.20.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.precura.be\/wp-content\/uploads\/\/2020\/10\/Precura-Verzekeringen-Logo-.svg\u00a0\u00bb title_text=\u00a0\u00bbPrecura-Verzekeringen-Logo-\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb40%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #0066b3;\">On s&rsquo;occupe de demain<\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#f8f8f8&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/wecoach.be\/nl\/detail\/health-screening-2-0-introductie\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Precura soutient la formation des chiens guides d\u2019aveugles<\/h2>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/www.precura.be\/wp-content\/uploads\/2025\/05\/begeleider-hond.jpg\u00a0\u00bb title_text=\u00a0\u00bbbegeleider-hond\u00a0\u00bb show_bottom_space=\u00a0\u00bboff\u00a0\u00bb force_fullwidth=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|36%|0px|36%|false|true\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_5,3_5,1_5&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#f8f8f8&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb|||-26px||\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Chez Precura, l&rsquo;engagement se vit au quotidien<\/h2>\n<p>Chez Precura, la durabilit\u00e9 et l\u2019engagement social ne sont pas de simples mots \u00e0 la mode : ce sont des valeurs que nous mettons en action chaque ann\u00e9e, avec c\u0153ur et conviction. Parmi les belles initiatives que nous soutenons, il y a un projet qui nous tient particuli\u00e8rement \u00e0 c\u0153ur : la formation de chiens guides d\u2019aveugles.<\/p>\n<h2><strong>Comment se d\u00e9roule la formation d&rsquo;un chien guide d&rsquo;aveugle?<\/strong><\/h2>\n<p>La formation est un processus intensif et m\u00e9ticuleux. Tous les chiens \u00e0 potentiel ne deviennent pas des chiens guide \u00e0 part enti\u00e8re, car le succ\u00e8s d\u00e9pend du lien fort et r\u00e9ciproque entre le chien et son ma\u00eetre, fond\u00e9 sur le respect et la confiance. Le parcours commence lorsque les chiots sont \u00e2g\u00e9s de deux mois. Ils sont alors \u00e9valu\u00e9s pour d\u00e9terminer s&rsquo;ils sont aptes \u00e0 devenir des chiens guide d&rsquo;aveugle. Les chiots qui r\u00e9ussissent sont alors confi\u00e9s \u00e0 une famille d&rsquo;accueil o\u00f9 ils sont socialis\u00e9s et \u00e9lev\u00e9s pendant 12 mois, avec les conseils du centre. Tous les frais li\u00e9s \u00e0 cette p\u00e9riode sont enti\u00e8rement pris en charge par le centre. \u00c0 l&rsquo;\u00e2ge de 14 mois, les chiens commencent leur formation au centre. Avec un instructeur, ils apprennent \u00e0 manier un harnais et un b\u00e2ton blanc. Les huit mois de formation sont suivis d&rsquo;une p\u00e9riode d&rsquo;entra\u00eenement avec le futur propri\u00e9taire. Le chien-guide est \u00e2g\u00e9 d&rsquo;environ deux ans a la fin de la formation.[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb|||-26px||\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Quel est le co\u00fbt d&rsquo;une telle formation?<\/h2>\n<p>En 2025, le co\u00fbt total pour former un chien guide s\u2019\u00e9l\u00e8ve \u00e0 43 500 \u20ac. Une partie est financ\u00e9e par le \u00ab\u00a0Vlaams Agentschap voor Personen met een Handicap (VAPH)\u00a0\u00bb, mais le reste d\u00e9pend des dons.  Gr\u00e2ce \u00e0 ces soutiens, les personnes malvoyantes peuvent b\u00e9n\u00e9ficier gratuitement d\u2019un compagnon fid\u00e8le qui leur offre autonomie et inclusion dans la vie sociale et professionnelle.[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb|||-26px||\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Qu&rsquo;est-ce que l&rsquo;action \u00ab\u00a0bouchon\u00a0\u00bb?<\/h2>\n<p>Parmi les fa\u00e7ons simples de contribuer, il y a l\u2019action \u00ab\u00a0bouchon\u00a0\u00bb ! Cette initiative \u00e9cologique est ouverte \u00e0 tous : particuliers, \u00e9coles, entreprises&#8230; Le principe? Rassembler des bouchons et couvercles en plastique (sans carton ni m\u00e9tal) et les d\u00e9poser dans un point de collecte. Transform\u00e9s en granul\u00e9s, ils deviennent la mati\u00e8re premi\u00e8re de nouveaux objets (poubelles, jeux pour enfants, gobelets&#8230;).<\/p>\n<p>Un kilo de bouchons rapporte 0,30 \u20ac, soit 300 \u20ac pour 1 000 kg. Il faut 83 333 kg pour financer un seul chien guide&#8230; autant dire que chaque bouchon compte ![\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb|||-26px||\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\">Envie de faire la diff\u00e9rence ?<\/h3>\n<p style=\"text-align: center;\">Pour en savoir plus ou participer \u00e0 cette belle initiative, rendez-vous sur le<br \/>\nsite. Ensemble, faisons la diff\u00e9rence \u2013 un bouchon \u00e0 la fois !<br \/>\n<strong>Source: <a href=\"https:\/\/geleidehond.be\/fr\/help-ons-helpen\/dopjesactie.html\">https:\/\/geleidehond.be\/fr\/help-ons-helpen\/dopjesactie.html<\/a><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb|||-26px||\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.precura.be\/wp-content\/uploads\/2025\/02\/revenus-garantis--300x300.jpg\" width=\"221\" height=\"221\" alt=\"\" class=\"wp-image-5222 alignnone size-medium\" srcset=\"https:\/\/www.precura.be\/wp-content\/uploads\/2025\/02\/revenus-garantis--300x300.jpg 300w, https:\/\/www.precura.be\/wp-content\/uploads\/2025\/02\/revenus-garantis--150x150.jpg 150w, https:\/\/www.precura.be\/wp-content\/uploads\/2025\/02\/revenus-garantis-.jpg 400w\" sizes=\"(max-width: 221px) 100vw, 221px\" \/><\/p>\n<h2>Profession lib\u00e9rale ou ind\u00e9pendante au sein d&rsquo;une soci\u00e9t\u00e9 ?<\/h2>\n<p><strong>Cela peut avoir des cons\u00e9quences sur votre police d&rsquo;assurance incapacit\u00e9 de travail.<\/strong><span style=\"font-weight: 400;\"><\/span><\/p>\n<h3>Pourquoi choisir une assurance chiffre d&rsquo;affaires?<\/h3>\n<p>Si, en tant que chef d&rsquo;entreprise, vous devenez temporairement inapte au travail, le chiffre d&rsquo;affaires de votre soci\u00e9t\u00e9 est menac\u00e9. L&rsquo;assurance chiffre d&rsquo;affaires offre alors la s\u00e9curit\u00e9 n\u00e9cessaire:<\/p>\n<ul>\n<li>Les frais fixes de votre entreprise seront couverts.<\/li>\n<li>Vous \u00e9vitez la pression financi\u00e8re pesant dans la gestion de votre entreprise et\/ou de vos collaborateurs.<\/li>\n<li>Vous gardez une plus grande tranquillit\u00e9 d&rsquo;esprit dans une p\u00e9riode o\u00f9 les d\u00e9fis ne manquent pas.<\/li>\n<\/ul>\n<h3>Besoin de conseils?<\/h3>\n<p>Nous nous ferons un plaisir de vous aider. Nos experts examineront votre situation personnelle et trouveront une solution sur mesure. N&rsquo;h\u00e9sitez pas \u00e0 nous envoyer un e-mail \u00e0 <strong><a href=\"mailto:business@precura.be\">business@precura.be<\/a><\/strong> \u2013 nous vous donnerons une r\u00e9ponse claire et pr\u00e9cise.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; Chiens guides d\u2019aveugles<br \/>\n&#8211; L&rsquo;action \u00ab\u00a0bouchon\u00a0\u00bb<br \/>\n&#8211; Assurance chiffre d&rsquo;affaires<\/p>\n","protected":false},"author":9,"featured_media":5289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-5295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletters-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Newsletter Avril 2025 - Precura<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Newsletter Avril 2025 - Precura\" \/>\n<meta property=\"og:description\" content=\"- Chiens guides d\u2019aveugles - L&#039;action &quot;bouchon&quot; - Assurance chiffre d&#039;affaires\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Precura\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-06T09:29:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T10:02:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.precura.be\/wp-content\/uploads\/2025\/05\/begeleider-hond.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"649\" \/>\n\t<meta property=\"og:image:height\" content=\"527\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"areagency\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"areagency\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.precura.be\\\/fr\\\/newsletter-avril-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.precura.be\\\/fr\\\/newsletter-avril-2025\\\/\"},\"author\":{\"name\":\"areagency\",\"@id\":\"https:\\\/\\\/www.precura.be\\\/#\\\/schema\\\/person\\\/dd3814164107b0893afdef26339d70d9\"},\"headline\":\"Newsletter Avril 2025\",\"datePublished\":\"2025-05-06T09:29:33+00:00\",\"dateModified\":\"2025-05-06T10:02:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.precura.be\\\/fr\\\/newsletter-avril-2025\\\/\"},\"wordCount\":1063,\"publisher\":{\"@id\":\"https:\\\/\\\/www.precura.be\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.precura.be\\\/fr\\\/newsletter-avril-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.precura.be\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/begeleider-hond.jpg\",\"articleSection\":[\"Newsletters\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.precura.be\\\/fr\\\/newsletter-avril-2025\\\/\",\"url\":\"https:\\\/\\\/www.precura.be\\\/fr\\\/newsletter-avril-2025\\\/\",\"name\":\"Newsletter Avril 2025 - Precura\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.precura.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.precura.be\\\/fr\\\/newsletter-avril-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.precura.be\\\/fr\\\/newsletter-avril-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.precura.be\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/begeleider-hond.jpg\",\"datePublished\":\"2025-05-06T09:29:33+00:00\",\"dateModified\":\"2025-05-06T10:02:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.precura.be\\\/fr\\\/newsletter-avril-2025\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.precura.be\\\/fr\\\/newsletter-avril-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.precura.be\\\/fr\\\/newsletter-avril-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.precura.be\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/begeleider-hond.jpg\",\"contentUrl\":\"https:\\\/\\\/www.precura.be\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/begeleider-hond.jpg\",\"width\":649,\"height\":527},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.precura.be\\\/fr\\\/newsletter-avril-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.precura.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsletter Avril 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.precura.be\\\/#website\",\"url\":\"https:\\\/\\\/www.precura.be\\\/\",\"name\":\"Precura\",\"description\":\"Precura est un partenaire fiable et exp\u00e9riment\u00e9 qui propose des assurances individuelles et collectives revenu garanti aux professions lib\u00e9rales. De quoi profiter d\u2019une tranquillit\u00e9 financi\u00e8re tout au long de votre carri\u00e8re.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.precura.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.precura.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.precura.be\\\/#organization\",\"name\":\"Precura\",\"url\":\"https:\\\/\\\/www.precura.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.precura.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.precura.be\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Precura-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.precura.be\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Precura-logo.svg\",\"width\":142,\"height\":66,\"caption\":\"Precura\"},\"image\":{\"@id\":\"https:\\\/\\\/www.precura.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.precura.be\\\/#\\\/schema\\\/person\\\/dd3814164107b0893afdef26339d70d9\",\"name\":\"areagency\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/661665dae7e7f562d06c1dddf0eaa3d4c282145e80252726a8de17e2179f9ea8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/661665dae7e7f562d06c1dddf0eaa3d4c282145e80252726a8de17e2179f9ea8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/661665dae7e7f562d06c1dddf0eaa3d4c282145e80252726a8de17e2179f9ea8?s=96&d=mm&r=g\",\"caption\":\"areagency\"},\"url\":\"https:\\\/\\\/www.precura.be\\\/fr\\\/author\\\/are-agency-webmaster\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Newsletter Avril 2025 - Precura","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"Newsletter Avril 2025 - Precura","og_description":"- Chiens guides d\u2019aveugles - L'action \"bouchon\" - Assurance chiffre d'affaires","og_url":"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/","og_site_name":"Precura","article_published_time":"2025-05-06T09:29:33+00:00","article_modified_time":"2025-05-06T10:02:56+00:00","og_image":[{"width":649,"height":527,"url":"https:\/\/www.precura.be\/wp-content\/uploads\/2025\/05\/begeleider-hond.jpg","type":"image\/jpeg"}],"author":"areagency","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"areagency","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/#article","isPartOf":{"@id":"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/"},"author":{"name":"areagency","@id":"https:\/\/www.precura.be\/#\/schema\/person\/dd3814164107b0893afdef26339d70d9"},"headline":"Newsletter Avril 2025","datePublished":"2025-05-06T09:29:33+00:00","dateModified":"2025-05-06T10:02:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/"},"wordCount":1063,"publisher":{"@id":"https:\/\/www.precura.be\/#organization"},"image":{"@id":"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.precura.be\/wp-content\/uploads\/2025\/05\/begeleider-hond.jpg","articleSection":["Newsletters"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/","url":"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/","name":"Newsletter Avril 2025 - Precura","isPartOf":{"@id":"https:\/\/www.precura.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.precura.be\/wp-content\/uploads\/2025\/05\/begeleider-hond.jpg","datePublished":"2025-05-06T09:29:33+00:00","dateModified":"2025-05-06T10:02:56+00:00","breadcrumb":{"@id":"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/#primaryimage","url":"https:\/\/www.precura.be\/wp-content\/uploads\/2025\/05\/begeleider-hond.jpg","contentUrl":"https:\/\/www.precura.be\/wp-content\/uploads\/2025\/05\/begeleider-hond.jpg","width":649,"height":527},{"@type":"BreadcrumbList","@id":"https:\/\/www.precura.be\/fr\/newsletter-avril-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.precura.be\/"},{"@type":"ListItem","position":2,"name":"Newsletter Avril 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.precura.be\/#website","url":"https:\/\/www.precura.be\/","name":"Precura","description":"Precura est un partenaire fiable et exp\u00e9riment\u00e9 qui propose des assurances individuelles et collectives revenu garanti aux professions lib\u00e9rales. De quoi profiter d\u2019une tranquillit\u00e9 financi\u00e8re tout au long de votre carri\u00e8re.","publisher":{"@id":"https:\/\/www.precura.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.precura.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.precura.be\/#organization","name":"Precura","url":"https:\/\/www.precura.be\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.precura.be\/#\/schema\/logo\/image\/","url":"https:\/\/www.precura.be\/wp-content\/uploads\/2020\/09\/Precura-logo.svg","contentUrl":"https:\/\/www.precura.be\/wp-content\/uploads\/2020\/09\/Precura-logo.svg","width":142,"height":66,"caption":"Precura"},"image":{"@id":"https:\/\/www.precura.be\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.precura.be\/#\/schema\/person\/dd3814164107b0893afdef26339d70d9","name":"areagency","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/661665dae7e7f562d06c1dddf0eaa3d4c282145e80252726a8de17e2179f9ea8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/661665dae7e7f562d06c1dddf0eaa3d4c282145e80252726a8de17e2179f9ea8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/661665dae7e7f562d06c1dddf0eaa3d4c282145e80252726a8de17e2179f9ea8?s=96&d=mm&r=g","caption":"areagency"},"url":"https:\/\/www.precura.be\/fr\/author\/are-agency-webmaster\/"}]}},"_links":{"self":[{"href":"https:\/\/www.precura.be\/fr\/wp-json\/wp\/v2\/posts\/5295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.precura.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.precura.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.precura.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.precura.be\/fr\/wp-json\/wp\/v2\/comments?post=5295"}],"version-history":[{"count":9,"href":"https:\/\/www.precura.be\/fr\/wp-json\/wp\/v2\/posts\/5295\/revisions"}],"predecessor-version":[{"id":5307,"href":"https:\/\/www.precura.be\/fr\/wp-json\/wp\/v2\/posts\/5295\/revisions\/5307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.precura.be\/fr\/wp-json\/wp\/v2\/media\/5289"}],"wp:attachment":[{"href":"https:\/\/www.precura.be\/fr\/wp-json\/wp\/v2\/media?parent=5295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.precura.be\/fr\/wp-json\/wp\/v2\/categories?post=5295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.precura.be\/fr\/wp-json\/wp\/v2\/tags?post=5295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}